{"id":89,"count":83,"description":"","link":"https:\/\/www.meenzer-on-tour.de\/blog\/tag\/reisen\/","name":"Reisen","slug":"reisen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reisen Archive - Meenzer on Tour Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meenzer-on-tour.de\/blog\/tag\/reisen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reisen Archive - Meenzer on Tour Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meenzer-on-tour.de\/blog\/tag\/reisen\/\" \/>\n<meta property=\"og:site_name\" content=\"Meenzer on Tour Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.meenzer-on-tour.de\/blog\/wp-content\/uploads\/2021\/08\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/tag\\\/reisen\\\/\",\"url\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/tag\\\/reisen\\\/\",\"name\":\"Reisen Archive - Meenzer on Tour Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/tag\\\/reisen\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/tag\\\/reisen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reisen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/\",\"name\":\"Meenzer on Tour Blog\",\"description\":\"Reisen - Fankultur - B&uuml;cher - Mainz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/#\\\/schema\\\/person\\\/e8a97e9efa1062d69a2cbb01f96b919f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/#\\\/schema\\\/person\\\/e8a97e9efa1062d69a2cbb01f96b919f\",\"name\":\"Christoph\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg\",\"url\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg\",\"width\":2000,\"height\":1200,\"caption\":\"Christoph\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.meenzer-on-tour.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reisen Archive - Meenzer on Tour Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meenzer-on-tour.de\/blog\/tag\/reisen\/","og_locale":"de_DE","og_type":"article","og_title":"Reisen Archive - Meenzer on Tour Blog","og_url":"https:\/\/www.meenzer-on-tour.de\/blog\/tag\/reisen\/","og_site_name":"Meenzer on Tour Blog","og_image":[{"width":2000,"height":1200,"url":"https:\/\/www.meenzer-on-tour.de\/blog\/wp-content\/uploads\/2021\/08\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.meenzer-on-tour.de\/blog\/tag\/reisen\/","url":"https:\/\/www.meenzer-on-tour.de\/blog\/tag\/reisen\/","name":"Reisen Archive - Meenzer on Tour Blog","isPartOf":{"@id":"https:\/\/www.meenzer-on-tour.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.meenzer-on-tour.de\/blog\/tag\/reisen\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.meenzer-on-tour.de\/blog\/tag\/reisen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.meenzer-on-tour.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Reisen"}]},{"@type":"WebSite","@id":"https:\/\/www.meenzer-on-tour.de\/blog\/#website","url":"https:\/\/www.meenzer-on-tour.de\/blog\/","name":"Meenzer on Tour Blog","description":"Reisen - Fankultur - B&uuml;cher - Mainz","publisher":{"@id":"https:\/\/www.meenzer-on-tour.de\/blog\/#\/schema\/person\/e8a97e9efa1062d69a2cbb01f96b919f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meenzer-on-tour.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.meenzer-on-tour.de\/blog\/#\/schema\/person\/e8a97e9efa1062d69a2cbb01f96b919f","name":"Christoph","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.meenzer-on-tour.de\/blog\/wp-content\/uploads\/2021\/08\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg","url":"https:\/\/www.meenzer-on-tour.de\/blog\/wp-content\/uploads\/2021\/08\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg","contentUrl":"https:\/\/www.meenzer-on-tour.de\/blog\/wp-content\/uploads\/2021\/08\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg","width":2000,"height":1200,"caption":"Christoph"},"logo":{"@id":"https:\/\/www.meenzer-on-tour.de\/blog\/wp-content\/uploads\/2021\/08\/A107190A-FC35-48EA-8B44-CF4EB9117345.jpeg"}}]}},"_links":{"self":[{"href":"https:\/\/www.meenzer-on-tour.de\/blog\/wp-json\/wp\/v2\/tags\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meenzer-on-tour.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.meenzer-on-tour.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.meenzer-on-tour.de\/blog\/wp-json\/wp\/v2\/posts?tags=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}